{"id":1875,"count":1,"description":"","link":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/","name":"The Animation Guild","slug":"the-animation-guild","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Animation Guild Archives - 47 Blog | AFM Local 47<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Animation Guild Archives - 47 Blog | AFM Local 47\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/\" \/>\n<meta property=\"og:site_name\" content=\"47 Blog | AFM Local 47\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afm47.org\/press\/wp-content\/uploads\/2015\/07\/AFM_Local_47_Logo_Blue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2238\" \/>\n\t<meta property=\"og:image:height\" content=\"1935\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@afmlocal47\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/tag\\\/the-animation-guild\\\/\",\"url\":\"https:\\\/\\\/afm47.org\\\/press\\\/tag\\\/the-animation-guild\\\/\",\"name\":\"The Animation Guild Archives - 47 Blog | AFM Local 47\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/tag\\\/the-animation-guild\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/tag\\\/the-animation-guild\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/afm47.org\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Animation Guild\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/afm47.org\\\/press\\\/\",\"name\":\"47 Blog | AFM Local 47\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/afm47.org\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#organization\",\"name\":\"American Federation of Musicians Local 47\",\"url\":\"https:\\\/\\\/afm47.org\\\/press\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/afm47.org\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/AFM_Local_47_Logo_Blue.jpg\",\"contentUrl\":\"https:\\\/\\\/afm47.org\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/AFM_Local_47_Logo_Blue.jpg\",\"width\":2238,\"height\":1935,\"caption\":\"American Federation of Musicians Local 47\"},\"image\":{\"@id\":\"https:\\\/\\\/afm47.org\\\/press\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/afmlocal47\",\"https:\\\/\\\/x.com\\\/afmlocal47\",\"https:\\\/\\\/instagram.com\\\/afmlocal47\",\"https:\\\/\\\/bsky.app\\\/profile\\\/afmlocal47.bsky.social\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/professional-musicians-local-47\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Animation Guild Archives - 47 Blog | AFM Local 47","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/","og_locale":"en_US","og_type":"article","og_title":"The Animation Guild Archives - 47 Blog | AFM Local 47","og_url":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/","og_site_name":"47 Blog | AFM Local 47","og_image":[{"width":2238,"height":1935,"url":"https:\/\/afm47.org\/press\/wp-content\/uploads\/2015\/07\/AFM_Local_47_Logo_Blue.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@afmlocal47","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/","url":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/","name":"The Animation Guild Archives - 47 Blog | AFM Local 47","isPartOf":{"@id":"https:\/\/afm47.org\/press\/#website"},"breadcrumb":{"@id":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/afm47.org\/press\/tag\/the-animation-guild\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/afm47.org\/press\/"},{"@type":"ListItem","position":2,"name":"The Animation Guild"}]},{"@type":"WebSite","@id":"https:\/\/afm47.org\/press\/#website","url":"https:\/\/afm47.org\/press\/","name":"47 Blog | AFM Local 47","description":"","publisher":{"@id":"https:\/\/afm47.org\/press\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afm47.org\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/afm47.org\/press\/#organization","name":"American Federation of Musicians Local 47","url":"https:\/\/afm47.org\/press\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/afm47.org\/press\/#\/schema\/logo\/image\/","url":"https:\/\/afm47.org\/press\/wp-content\/uploads\/2015\/07\/AFM_Local_47_Logo_Blue.jpg","contentUrl":"https:\/\/afm47.org\/press\/wp-content\/uploads\/2015\/07\/AFM_Local_47_Logo_Blue.jpg","width":2238,"height":1935,"caption":"American Federation of Musicians Local 47"},"image":{"@id":"https:\/\/afm47.org\/press\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/afmlocal47","https:\/\/x.com\/afmlocal47","https:\/\/instagram.com\/afmlocal47","https:\/\/bsky.app\/profile\/afmlocal47.bsky.social","https:\/\/www.linkedin.com\/company\/professional-musicians-local-47\/"]}]}},"_links":{"self":[{"href":"https:\/\/afm47.org\/press\/wp-json\/wp\/v2\/tags\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afm47.org\/press\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/afm47.org\/press\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/afm47.org\/press\/wp-json\/wp\/v2\/posts?tags=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}